{"id":656,"date":"2026-03-25T01:53:47","date_gmt":"2026-03-25T01:53:47","guid":{"rendered":"https:\/\/639noticias.com\/?p=656"},"modified":"2026-03-25T01:53:47","modified_gmt":"2026-03-25T01:53:47","slug":"joven-que-mato-a-maestras-es-hijastro-de-soldado-de-la-marina","status":"publish","type":"post","link":"https:\/\/639noticias.com\/index.php\/2026\/03\/25\/joven-que-mato-a-maestras-es-hijastro-de-soldado-de-la-marina\/","title":{"rendered":"Joven que mat\u00f3 a maestras es hijastro de soldado de la Marina"},"content":{"rendered":"<p>Un jovencito de 15 a\u00f1os, alumno de la preparatoria Anton Makarenko de L\u00e1zaro C\u00e1rdenas, Michoac\u00e1n, asesin\u00f3 a dos maestras con un fusil AR-15 durante este martes.<\/p>\n<p>Los informes preliminares refieren que el menor de edad, hijastro de un elemento de la Marina-Armada de M\u00e9xico, perpetr\u00f3 el doble homicidio con un rifle de asalto AR-15, arma larga que persum\u00eda en videos de redes sociales.<\/p>\n<p>Seg\u00fan lo se\u00f1alado, el menor asesin\u00f3 a las maestras porque presuntamente \u201cno lo dejaron entrar y dijo que \u2018lo hostigaban\u2019\u201d.<\/p>\n<p>Testigos del atentado se\u00f1aloron que el joven ingres\u00f3 al plantel escolar y se fue directo contra las v\u00edctimas, a las que dispar\u00f3 con el fusil de asalto frente a los dem\u00e1s docentes y a la comunidad de la escuela.<\/p>\n<p>El joven fue detenido y entregado a personal de la Fiscal\u00eda de Michoac\u00e1n, para posteriormente ser puesto a disposici\u00f3n del Ministerio P\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un jovencito de 15 a\u00f1os, alumno de la preparatoria Anton Makarenko de L\u00e1zaro C\u00e1rdenas, Michoac\u00e1n, asesin\u00f3 a dos maestras con un fusil AR-15 durante este martes. Los informes preliminares refieren que el menor de edad, hijastro de un elemento de la Marina-Armada de M\u00e9xico, perpetr\u00f3 el doble homicidio con un rifle de asalto AR-15, arma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/posts\/656"}],"collection":[{"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=656"}],"version-history":[{"count":1,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/posts\/656\/revisions"}],"predecessor-version":[{"id":658,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/posts\/656\/revisions\/658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/media\/657"}],"wp:attachment":[{"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/639noticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}